{"id":35511,"date":"2025-03-10T18:39:02","date_gmt":"2025-03-10T17:39:02","guid":{"rendered":"https:\/\/alquiler.balearichomemallorca.com\/properties\/casa-restaurada-con-encanto-en-binisalem\/"},"modified":"2025-03-10T20:07:47","modified_gmt":"2025-03-10T19:07:47","slug":"casa-restaurada-con-encanto-en-binisalem","status":"publish","type":"estate_property","link":"https:\/\/alquiler.balearichomemallorca.com\/es\/properties\/casa-restaurada-con-encanto-en-binisalem\/","title":{"rendered":"Casa restaurada con encanto en Binisalem"},"content":{"rendered":"\n<p>CASA DE ALQUILER A CORTO PLAZO NO PARA VACACIONES.<br\/>Si buscas un alquiler a corto plazo y tener un lugar agradable para trabajar o estudiar.<br\/>Descubre una encantadora casa de alquiler en el pintoresco pueblo de Binissalem, situado en el coraz\u00f3n de Mallorca. Esta casa hist\u00f3rica, rica en car\u00e1cter y con vestigios del antiguo Imperio Romano, est\u00e1 situada en una regi\u00f3n famosa por su vino y sus rutas ciclistas.<\/p>\n\n<p>La casa adosada, revestida de piedra, cuenta con un impresionante patio con una refrescante piscina, perfecta para refrescarse en los d\u00edas m\u00e1s calurosos del a\u00f1o. Entrando desde la calle, te recibe un magn\u00edfico sal\u00f3n que en su d\u00eda fue un establo abovedado. Desde aqu\u00ed, tienes acceso a una cocina totalmente equipada y a un cuarto de ba\u00f1o con ducha. Los grandes ventanales de la espaciosa sala de estar dan al mencionado patio, que goza de abundante luz solar durante los meses de verano.<\/p>\n\n<p>Una elegante escalera met\u00e1lica te lleva a la segunda planta, donde encontrar\u00e1s un amplio sal\u00f3n con sof\u00e1s en forma de L, ideal para ver la tele o disfrutar de las vistas del campo mientras pasas tiempo con los amigos o la familia. Unos escalones m\u00e1s arriba conducen a un amplio dormitorio con cama de matrimonio, y al otro lado del pasillo hay un generoso cuarto de ba\u00f1o con ba\u00f1era.<\/p>\n\n<p>Todos los materiales utilizados en la renovaci\u00f3n de esta casa centenaria han sido reciclados o reutilizados, y estaremos encantados de mostrarte los detalles de esta cuidada restauraci\u00f3n.<\/p>\n\n<p>Aunque la propiedad no dispone de aparcamiento privado, hay un amplio aparcamiento al aire libre justo delante de la puerta. \u00a1No pierdas la oportunidad de experimentar esta casa \u00fanica en un entorno precioso!<\/p>\n\n<p>PRECIOS MENSUALES POR TEMPORADA: ( comisi\u00f3n de agencia no incluida)<br\/>6.000\u20ac MES EN JULIO Y AGOSTO<br\/>3.500\u20ac MES EL RESTO DEL A\u00d1O.<\/p>\n\n<p>\u00daltima limpieza 150 euros<\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASA DE ALQUILER A CORTO PLAZO NO PARA VACACIONES.Si buscas un alquiler a corto plazo y tener un lugar agradable para trabajar o estudiar.Descubre una encantadora casa de alquiler en el pintoresco pueblo de Binissalem, situado en el coraz\u00f3n de Mallorca. Esta casa hist\u00f3rica, rica en car\u00e1cter y con vestigios del antiguo Imperio Romano, est\u00e1 situada en una regi\u00f3n famosa por su vino y &#8230;<\/p>\n","protected":false},"featured_media":35555,"comment_status":"open","ping_status":"closed","template":"","property_category":[154],"property_action_category":[310],"property_city":[362],"property_area":[],"property_county_state":[68],"property_features":[158,162,173,175],"property_status":[],"class_list":["post-35511","estate_property","type-estate_property","status-publish","has-post-thumbnail","hentry","property_category-villas-es","property_action_category-alquiler-a-largo-plazo","property_city-binisalem-es","property_county_state-spain","property_features-aacc-es","property_features-chimenea-es","property_features-piscina-es","property_features-terraza-es"],"_links":{"self":[{"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/estate_property\/35511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/estate_property"}],"about":[{"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/types\/estate_property"}],"replies":[{"embeddable":true,"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/comments?post=35511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/media\/35555"}],"wp:attachment":[{"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/media?parent=35511"}],"wp:term":[{"taxonomy":"property_category","embeddable":true,"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/property_category?post=35511"},{"taxonomy":"property_action_category","embeddable":true,"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/property_action_category?post=35511"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/property_city?post=35511"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/property_area?post=35511"},{"taxonomy":"property_county_state","embeddable":true,"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/property_county_state?post=35511"},{"taxonomy":"property_features","embeddable":true,"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/property_features?post=35511"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/alquiler.balearichomemallorca.com\/es\/wp-json\/wp\/v2\/property_status?post=35511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}